{"id":3235,"date":"2017-06-09T11:00:37","date_gmt":"2017-06-09T15:00:37","guid":{"rendered":"http:\/\/noticias.arquidiocesisd.org\/?p=3235"},"modified":"2026-04-17T15:04:03","modified_gmt":"2026-04-17T15:04:03","slug":"papa-francisco-ofrece-una-receta-cuando-estemos-momentos-oscuridad","status":"publish","type":"post","link":"https:\/\/diariocatolico.org\/index.php\/2017\/06\/09\/papa-francisco-ofrece-una-receta-cuando-estemos-momentos-oscuridad\/","title":{"rendered":"Papa Francisco ofrece una receta para cuando estemos en momentos de oscuridad"},"content":{"rendered":"<p>Rezar y tener paciencia. Esta es la receta que el Papa Francisco ofreci\u00f3 en la homil\u00eda de la Misa en la Casa Santa Marta para hacer frente a momentos dif\u00edciles y de oscuridad.<\/p>\n<p>El Pont\u00edfice alert\u00f3 adem\u00e1s contra la vanidad que es una \u201cbelleza maquillada\u201d que no dejar entrar en el coraz\u00f3n la \u201calegr\u00eda que es de Dios\u201d.<\/p>\n<p>En la Misa en la capilla de la Casa Santa Marta, el Pont\u00edfice invit\u00f3 a dar gracias por la \u201csalvaci\u00f3n\u201d que nos da al comentar la primera lectura de la liturgia del d\u00eda.<\/p>\n<p>Dios \u201clleva adelante la historia\u201d y \u201cla vida de las personas, tambi\u00e9n la nuestra\u201d, afirm\u00f3. A continuaci\u00f3n record\u00f3 que Tob\u00edas y Sara vivieron \u201cmomentos dif\u00edciles\u201d y \u201cmomentos hermosos\u201d, como en \u201ctoda la vida\u201d.<\/p>\n<p>\u201cTodos nosotros hemos pasado por momentos feos, fuertes; sabemos lo que se siente en un momento de oscuridad, en el momento de dolor, en el momento de las dificultades, lo sabemos\u201d.<\/p>\n<p>Pero Tob\u00edas y Sara rezan y \u201cesta es la actitud que nos salva de los momentos feos: la oraci\u00f3n. La paciencia: porque ambas son pacientes con el propio dolor. Y la esperanza de que Dios nos escuche y nos haga pasar estos momentos feos. En los momentos de tristeza, poca o mucha, en los momentos de oscuridad: oraci\u00f3n, paciencia y esperanza. No hay que olvidar esto\u201d, dijo el Papa.<\/p>\n<p>\u201cDespu\u00e9s de la prueba, el Se\u00f1or se hace cercano a ellos y los salva. Pero hay momentos hermosos, aut\u00e9nticos, como este, no momentos con la belleza maquillada, que todo es artificial, fuegos artificiales, pero no es la belleza del coraz\u00f3n\u201d.<\/p>\n<p>\u201c\u00bfY qu\u00e9 hacen estos dos momentos hermosos?\u201d, se pregunt\u00f3. \u201cDan gracias a Dios, alargan el coraz\u00f3n en la oraci\u00f3n y en el agradecimiento\u201d.<\/p>\n<p>En este sentido, invit\u00f3 a discernir que en la vida hay momentos de \u201ccruz\u201d en los que es necesario \u201corar, tener paciencia y tener al menos un poco de esperanza\u201d: se necesita evitar caer \u201cen la vanidad\u201d porque \u201csiempre est\u00e1 el Se\u00f1or\u201d con nosotros.<\/p>\n<p>\u201cPidamos la gracia de saber discernir qu\u00e9 sucede en los momentos feos de nuetsra vida y como ir adelante, y qu\u00e9 ocurre en los momentos hermosos y no dejarnos enga\u00f1ar por la vanidad\u201d.<\/p>\n<p>Lectura comentada por el Papa:<\/p>\n<p>Primera lectura<\/p>\n<p>Tob\u00edas 11:5-17<br \/>\n5\u00a0Estaba Ana sentada, con la mirada fija en el camino de su hijo.<br \/>\n6\u00a0Tuvo la corazonada de que \u00e9l ven\u00eda y dijo al padre: \u00abMira, ya viene tu hijo y el hombre que le acompa\u00f1aba.\u00bb<br \/>\n7\u00a0Rafael iba diciendo a Tob\u00edas, mientras se acercaban al padre: \u00abTengo por seguro que se abrir\u00e1n los ojos de tu padre.<br \/>\n8\u00a0Untale los ojos con la hiel del pez, y el remedio har\u00e1 que las manchas blancas se contraigan y se le caer\u00e1n como escamos de los ojos. Y as\u00ed tu padre podr\u00e1 mirar y ver la luz.\u00bb<br \/>\n9\u00a0Corri\u00f3 Ana y se ech\u00f3 al cuello de su hijo, diciendo: \u00ab\u00a1Ya te he visto, hijo! \u00a1Ya puedo morir!\u00bb Y rompi\u00f3 a llorar.<br \/>\n10\u00a0Tobit se levant\u00f3 y trompicando sali\u00f3 a la puerta del patio.<br \/>\n11\u00a0Corri\u00f3 hacia \u00e9l Tob\u00edas, llevando en la mano la hiel del pez; le sopl\u00f3 en los ojos y abraz\u00e1ndole estrechamente le dijo: \u00ab\u00a1Ten confianza, padre!\u00bb Y le aplic\u00f3 el remedio y esper\u00f3;<br \/>\n12\u00a0y luego, con ambas manos le quit\u00f3 las escamas de la comisura de los ojos.<br \/>\n13\u00a0Entonces \u00e9l se arroj\u00f3 a su cuello, llor\u00f3 y le dijo: \u00ab\u00a1Ahora te veo, hijo, luz de mis ojos!\u00bb<br \/>\n14\u00a0Y a\u00f1adi\u00f3: \u00a1Bendito sea Dios! \u00a1Bendito su gran Nombre! \u00a1Bendito todos sus santos \u00e1ngeles! \u00a1Bendito su gran Nombre por todos los siglos!<br \/>\n15\u00a0Porque me hab\u00eda azotado, pero me tiene piedad y ahora veo a mi hijo Tob\u00edas. Tob\u00edas entr\u00f3 en casa lleno de gozo y bendiciendo a Dios con toda su voz; luego cont\u00f3 a su padre el \u00e9xito de su viaje, c\u00f3mo tra\u00eda el dinero y c\u00f3mo se hab\u00eda casado con Sarra, la hija de Rag\u00fcel, y que ven\u00eda ella con \u00e9l y estaba ya a las puertas de N\u00ednive.<br \/>\n16\u00a0Tobit sali\u00f3 al encuentro de su nuera hasta las puertas de N\u00ednive, bendiciendo a Dios, lleno de gozo. Cuando los de N\u00ednive le vieron caminar, avanzando con su antigua firmeza, sin necesidad de lazarillo, se maravillaron. Tobit proclam\u00f3 delante de ellos que Dios se hab\u00eda compadecido de \u00e9l y le hab\u00eda abierto los ojos.<br \/>\n17\u00a0Se acerc\u00f3 Tobit a Sarra, la mujer de su hijo, y la bendijo diciendo: \u00ab\u00a1Bienvenida seas, hija! Y bendito sea tu Dios, hija, que te ha tra\u00eddo hasta nosotros. Bendito sea tu padre, y bendito Tob\u00edas, mi hijo, y bendita t\u00fa misma, hija. Bienvenida seas, entra en tu casa con gozo y bendici\u00f3n.\u00bb<\/p>\n<p>Tambi\u00e9n te puede interesar:<\/p>\n<p>El Papa Francisco apoya al Episcopado y al pueblo de Venezuela, afirma Mons. Padr\u00f3n https:\/\/t.co\/ggOmhih4Bo<\/p>\n<p>\u2014 ACI Prensa (@aciprensa) 8 de junio de 2017<br \/>\nFuente: ACI Prensa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rezar y tener paciencia. Esta es la receta que el Papa Francisco ofreci\u00f3 en la&hellip;<\/p>\n","protected":false},"author":1,"featured_media":3236,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-3235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts\/3235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/comments?post=3235"}],"version-history":[{"count":0,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts\/3235\/revisions"}],"wp:attachment":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/media?parent=3235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/categories?post=3235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/tags?post=3235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}