{"id":4290,"date":"2017-10-09T09:10:13","date_gmt":"2017-10-09T13:40:13","guid":{"rendered":"http:\/\/noticias.arquidiocesisd.org\/?p=4290"},"modified":"2026-04-17T15:04:04","modified_gmt":"2026-04-17T15:04:04","slug":"4290-2","status":"publish","type":"post","link":"https:\/\/diariocatolico.org\/index.php\/2017\/10\/09\/4290-2\/","title":{"rendered":"El Papa advierte sobre el da\u00f1o que la pornograf\u00eda en Internet hace a los menores"},"content":{"rendered":"<p>Durante su discurso el Papa Francisco ha alertado sobre el serio peligro que corren los menores de edad ante la propagaci\u00f3n de la pornograf\u00eda en Internet.<\/p>\n<ul>\n<li><a href=\"http:\/\/infocatolica.com\/?t=noticia&amp;cod=29935\">C\u00f3mo da\u00f1a el consumo de pornograf\u00eda al cerebro<\/a><\/li>\n<li><a href=\"http:\/\/infocatolica.com\/?t=noticia&amp;cod=30522\">El consumo de pornograf\u00eda aumenta la incidencia de la violencia sexual<\/a><\/li>\n<\/ul>\n<p>Durante un discurso a los participantes en un Congreso sobre \u00abLa dignidad del menor en el mundo digital\u00bb, el Papa Francisco ha alertado sobre el\u00a0<strong>serio peligro que corren los menores de edad ante la propagaci\u00f3n de la pornograf\u00eda<\/strong>\u00a0en Internet. A este respecto ha se\u00f1alado el Santo Padre que en la red \u00abse est\u00e1n propagando fen\u00f3menos extremadamente peligrosos\u00bb y entre ellos mencion\u00f3 \u00ab<strong>la difusi\u00f3n de im\u00e1genes pornogr\u00e1ficas<\/strong>\u00bb, el \u00ab<strong>creciente fen\u00f3meno del sexting<\/strong>\u00a0entre chicos y chicas que utilizan las redes sociales\u00bb, \u00ab<strong>la sextortion<\/strong>; la captaci\u00f3n a trav\u00e9s de la red de menores con fines sexuales\u00bb entre otros. <strong>Problema globalizado con el alcance del Internet<\/strong> El Papa recalc\u00f3 que la antigua difusi\u00f3n de la pornograf\u00eda a trav\u00e9s de medios impresos \u00abera un fen\u00f3meno de peque\u00f1as dimensiones comparado con lo que est\u00e1 sucediendo hoy en d\u00eda de una manera cada vez m\u00e1s creciente y r\u00e1pida, a trav\u00e9s de la red\u00bb, problema ante el cual \u00abninguna autoridad nacional por su cuenta se siente capaz de abarcar adecuadamente y de controlar las dimensiones y la evoluci\u00f3n de estos fen\u00f3menos\u00bb. Sin embargo, el Papa agrega que \u00abno debemos dejarnos dominar por el miedo\u00bb\u00a0<strong>ni \u00abdejar que nos paralice<\/strong>\u00a0el sentimiento de impotencia que nos oprime frente a la dificultad de la tarea\u00bb. Sino que estamos \u00ab<strong>llamados a movilizarnos juntos<\/strong>, sabiendo que nos necesitamos mutuamente para buscar y encontrar el camino y las actitudes adecuadas que ayuden a dar respuestas eficaces A este respecto el Papa invit\u00f3 a\u00a0<strong>no<\/strong>\u00a0\u00ab<strong>subestimar el da\u00f1o<\/strong>\u00a0que los fen\u00f3menos antes mencionados hacen a los menores\u00bb. En segundo lugar se\u00f1al\u00f3 como un error el de pensar \u00abque las soluciones t\u00e9cnicas autom\u00e1ticas, los filtros construidos en base a algoritmos cada vez m\u00e1s sofisticados para identificar y bloquear la difusi\u00f3n de im\u00e1genes abusivas y da\u00f1inas, son suficientes para hacer frente a los problemas\u00bb. Estas aunque \u00abson medidas necesarias, \u2026, tambi\u00e9n es necesario que, dentro de la din\u00e1mica misma del desarrollo t\u00e9cnico, sus actores y protagonistas\u00a0<strong>perciban con mayor urgencia, en toda su amplitud y en sus diversas implicaciones<\/strong>, la fuerza de la exigencia \u00e9tica\u00bb. Un tercer error que mencion\u00f3 el Papa es el de tener \u00ab<strong>una visi\u00f3n ideol\u00f3gica y m\u00edtica de la red como un reino de libertad sin l\u00edmites<\/strong>\u00bb. En este sentido, aunque la red \u00abha abierto un espacio nuevo y de gran alcance para la libre expresi\u00f3n y el intercambio de ideas e informaci\u00f3n\u00bb tambi\u00e9n \u00abha ofrecido\u00a0<strong>nuevos instrumentos para actividades il\u00edcitas horribles<\/strong>\u00a0y, en el \u00e1mbito que nos ocupa, para\u00a0<strong>el abuso y el da\u00f1o a la dignidad de los menores<\/strong>, para la corrupci\u00f3n de sus mentes y la violencia a sus cuerpos\u00bb. Por lo tanto, enfatiz\u00f3 el Papa, \u00abaqu\u00ed no se trata de ejercicio de la libertad,\u00a0<strong>sino de cr\u00edmenes, contra los cuales debemos proceder con inteligencia y determinaci\u00f3n<\/strong>, ampliando la cooperaci\u00f3n entre los gobiernos y las fuerzas del orden a nivel global, en la misma medida en que la red se ha hecho global\u00bb. Puede leer el discurso completo del Papa Francisco en el siguiente enlace: <a href=\"http:\/\/w2.vatican.va\/content\/francesco\/es\/speeches\/2017\/october\/documents\/papa-francesco_20171006_congresso-childdignity-digitalworld.html\">Discurso del Papa Francisco a los participantes en un congreso sobre \u00abLa dignidad del menor en el mundo digital\u00bb<\/a> <strong>Fuente:<\/strong>\u00a0infocatolica.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante su discurso el Papa Francisco ha alertado sobre el serio peligro que corren los&hellip;<\/p>\n","protected":false},"author":1,"featured_media":4289,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts\/4290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/comments?post=4290"}],"version-history":[{"count":0,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts\/4290\/revisions"}],"wp:attachment":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/media?parent=4290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/categories?post=4290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/tags?post=4290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}