{"id":5307,"date":"2017-11-30T08:51:27","date_gmt":"2017-11-30T13:21:27","guid":{"rendered":"https:\/\/www.diariocatolico.org\/?p=5307"},"modified":"2026-04-17T15:04:04","modified_gmt":"2026-04-17T15:04:04","slug":"no-se-puede-usar-dios-odio-la-violencia-la-division-afirma-papa","status":"publish","type":"post","link":"https:\/\/diariocatolico.org\/index.php\/2017\/11\/30\/no-se-puede-usar-dios-odio-la-violencia-la-division-afirma-papa\/","title":{"rendered":"No se puede usar a Dios para el odio, la violencia y la divisi\u00f3n, afirma el Papa"},"content":{"rendered":"<p>VATICANO, (<b><\/b><b><a href=\"http:\/\/www.aciprensa.com\/\">ACI<\/a><\/b>).- Durante su discurso a las autoridades, el Papa Francisco conden\u00f3 de nuevo el uso que algunos hacer de la religi\u00f3n para \u201cfomentar la divisi\u00f3n\u201d y la violencia.<!--more--><\/p>\n<p>En una clara alusi\u00f3n al terrorismo internacional yihadista, el Santo Padre afirm\u00f3: \u201cen un mundo en el que la religi\u00f3n a menudo se usa \u2013escandalosamente\u2013 para fomentar la divisi\u00f3n, el testimonio de su poder reconciliador y unificador es muy necesario\u201d.<\/p>\n<p>El Papa record\u00f3 adem\u00e1s el terrible ataque que tuvo lugar precisamente en Daca el 1 de julio de 2016 cuando cinco asaltantes abrieron fuego en un restaurante y una panader\u00eda de un barrio financiero de la capital, donde se encuentran tambi\u00e9n varias embajadas. All\u00ed, tomaron decenas de rehenes y mataron a varios agentes de polic\u00eda. Finalmente, los asaltantes fuero, abatidos.<\/p>\n<p>\u201cEsto se ha manifestado de manera particularmente elocuente en la reacci\u00f3n un\u00e1nime de indignaci\u00f3n que sigui\u00f3 al brutal ataque terrorista del a\u00f1o pasado aqu\u00ed en Dhaka, y en el claro mensaje que las autoridades religiosas de la naci\u00f3n han enviado de que el sant\u00edsimo nombre de Dios nunca se puede invocar para justificar el odio y la violencia contra otros seres humanos, nuestros semejantes\u201d, a\u00f1adi\u00f3 Francisco.<\/p>\n<p>Fuente: AciPrensa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VATICANO, (ACI).- Durante su discurso a las autoridades, el Papa Francisco conden\u00f3 de nuevo el&hellip;<\/p>\n","protected":false},"author":1,"featured_media":5308,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-5307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts\/5307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/comments?post=5307"}],"version-history":[{"count":0,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts\/5307\/revisions"}],"wp:attachment":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/media?parent=5307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/categories?post=5307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/tags?post=5307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}