{"id":5449,"date":"2017-12-07T11:15:18","date_gmt":"2017-12-07T15:45:18","guid":{"rendered":"https:\/\/www.diariocatolico.org\/?p=5449"},"modified":"2026-04-17T15:04:04","modified_gmt":"2026-04-17T15:04:04","slug":"papa-francisco-catolicos-luteranos-no-pueden-permitirse-rivales","status":"publish","type":"post","link":"https:\/\/diariocatolico.org\/index.php\/2017\/12\/07\/papa-francisco-catolicos-luteranos-no-pueden-permitirse-rivales\/","title":{"rendered":"Papa Francisco: \u201cCat\u00f3licos y luteranos no pueden permitirse ser rivales\u201d"},"content":{"rendered":"<p>VATICANO, 07 Dic. 17 (ACI).-<br \/>\nEl Papa Francisco, en un discurso dirigido a miembros de la Federaci\u00f3n Luterana Mundial en el Vaticano, afirm\u00f3 que cat\u00f3licos y luteranos \u201cno pueden permitirse ser adversarios o rivales\u201d, y exhort\u00f3 a \u201cbuscar y promover una mayor comuni\u00f3n en el amor y en la fe\u201d.<!--more--><\/p>\n<p>En su discurso, el Santo Padre hizo memoria del encuentro ecum\u00e9nico que mantuvo con los miembros de la Federaci\u00f3n Luterana Mundial en Lund el 31 de octubre de 2016 con motivo del A\u00f1o de la Conmemoraci\u00f3n de la Reforma.<\/p>\n<p>Francisco se\u00f1al\u00f3 el motivo por el que aquel encuentro de oraci\u00f3n ecum\u00e9nica result\u00f3 tan importante para la uni\u00f3n de los cristianos: \u201cEra importante encontrarse principalmente en la oraci\u00f3n, porque el don de la unidad entre creyentes germina y florece por la gracia de Dios, no en funci\u00f3n de proyectos humanos\u201d.<\/p>\n<p>\u201cS\u00f3lo rezando nos podremos custodiar unos a otros \u2013explic\u00f3\u2013. La oraci\u00f3n purifica, fortalece, ilumina el camino, nos hace ir adelante. La oraci\u00f3n es como el carburante de nuestro viaje hacia la plena unidad. De hecho, el amor del Se\u00f1or, que dibujamos rezando, pone en marcha la caridad que nos acerca\u201d.<\/p>\n<p>De esa oraci\u00f3n surge \u201cla paciencia de nuestra espera, el motivo de nuestra reconciliaci\u00f3n, la fuerza para seguir avanzando juntos\u201d.<\/p>\n<p>La Papa continu\u00f3: \u201cRezando podemos vernos los unos a los otros en la perspectiva justa: la del Padre\u201d. \u201cEn el Esp\u00edritu de Jes\u00fas, al cual rezamos, nos reconocemos como hermanos\u201d.<\/p>\n<p>Con ese esp\u00edritu de oraci\u00f3n y de fraternidad \u201cmiramos hacia la historia pasada y damos gracias a Dios porque las divisiones tan dolorosas que nos han distanciado y enfrentado durante siglos, en los \u00faltimos decenios han confluido en un camino de comuni\u00f3n, en el camino ecum\u00e9nico suscitado por el Esp\u00edritu Santo\u201d.<\/p>\n<p>Frente a las diferencias todav\u00eda presentes, el Pont\u00edfice destac\u00f3 \u201cla realidad presente, com\u00fan, fundacional y permanente de nuestro Bautismo, que nos hace hijos de Dios y hermanos entre nosotros\u201d.<\/p>\n<p>Por \u00faltimo, puso en relieve el ejemplo de los m\u00e1rtires. \u201cSon muchos, incluso en nuestros d\u00edas, los que sufren por dar testimonio de Jes\u00fas: su hero\u00edsmo pac\u00edfico es para nosotros una llamada urgente a una fraternidad siempre m\u00e1s real\u201d.<\/p>\n<p>Tambi\u00e9n te puede interesar:<\/p>\n<p>El Papa habla sobre la nueva traducci\u00f3n del Padre Nuestro en franc\u00e9s https:\/\/t.co\/QBXufvJgWI<\/p>\n<p>Fuente: AciPrensa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VATICANO, 07 Dic. 17 (ACI).- El Papa Francisco, en un discurso dirigido a miembros de&hellip;<\/p>\n","protected":false},"author":1,"featured_media":5464,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-5449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts\/5449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/comments?post=5449"}],"version-history":[{"count":0,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts\/5449\/revisions"}],"wp:attachment":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/media?parent=5449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/categories?post=5449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/tags?post=5449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}