{"id":5453,"date":"2017-12-07T13:14:55","date_gmt":"2017-12-07T17:44:55","guid":{"rendered":"https:\/\/www.diariocatolico.org\/?p=5453"},"modified":"2026-04-17T15:04:04","modified_gmt":"2026-04-17T15:04:04","slug":"asi-se-despidio-cardenal-rivera-tras-22-anos-arzobispo-mexico","status":"publish","type":"post","link":"https:\/\/diariocatolico.org\/index.php\/2017\/12\/07\/asi-se-despidio-cardenal-rivera-tras-22-anos-arzobispo-mexico\/","title":{"rendered":"As\u00ed se despidi\u00f3 el Cardenal Rivera tras 22 a\u00f1os como Arzobispo de M\u00e9xico"},"content":{"rendered":"<p>M\u00c9XICO, 07 Dic. 17 (ACI).-<br \/>\nLuego de conocerse el nombramiento del Cardenal Carlos Aguiar como nuevo Arzobispo de M\u00e9xico, el Cardenal Norberto Rivera Carrera se despidi\u00f3 de su di\u00f3cesis a trav\u00e9s de una carta en la que dese\u00f3 a su sucesor \u201ctodo bien en el Se\u00f1or, y que su ministerio episcopal sea fruct\u00edfero para mayor gloria de Dios Nuestro Se\u00f1or\u201d.<!--more--><\/p>\n<p>En la carta, el Cardenal Rivera Carrera afirma que se lleva la satisfacci\u00f3n \u201cde no haber permanecido mudo ante la violaci\u00f3n de los derechos humanos y divinos de mi madre la Iglesia. Lamento si, por mi posici\u00f3n firme, alguien se sinti\u00f3 ofendido y lastimado, y una vez m\u00e1s pido humildemente perd\u00f3n a quien, aun sin querer, haya ofendido\u201d.<\/p>\n<p>Se\u00f1ala que \u201csin m\u00e9rito alguno de mi parte, el Pastor de nuestras almas, Cristo Jes\u00fas, me quiso como gu\u00eda de esta enorme Arquidi\u00f3cesis, y para gobernarla cont\u00e9 con el apoyo de excelentes Obispos Auxiliares, un gran presbiterio con diversidad de dones y carismas, y un numeroso grupo de di\u00e1conos que sirven d\u00eda a d\u00eda con generosidad\u201d.<\/p>\n<p>Asimismo, reconoce \u201cla labor tan diversificada de mis hermanos de vida consagrada en favor del Evangelio\u201d, adem\u00e1s del \u201ccrecimiento y la preparaci\u00f3n de los laicos para ocupar el lugar que les corresponde en nuestra Iglesia\u201d,<\/p>\n<p>El Cardenal reconoce tambi\u00e9n los problemas y dificultades que debe afrontar \u201cesta Iglesia particular\u201d, \u201cpero es mucho mayor el gozo, la alegr\u00eda y la santificaci\u00f3n que tenemos quienes tratamos de servir a la causa del Evangelio\u201d.<\/p>\n<p>Para hacer frente al gobierno de la Arquidi\u00f3cesis durante 22 a\u00f1os, el Cardenal asegura en su carta que \u201csiempre cont\u00e9 con la cercan\u00eda y el amor maternal de mi Morenita del Tepeyac y el ejemplo de San Juan Diego, a quienes ahora elevo mis oraciones por el nuevo Arzobispo de M\u00e9xico\u201d.<\/p>\n<p>Finalmente, \u201cpido perd\u00f3n a Dios por mis debilidades y omisiones. Al final de mis d\u00edas espero encontrarme con mi Salvador, rico en Misericordia\u201d.<\/p>\n<p>El Cardenal Norberto Rivera Carrera naci\u00f3 en La Pur\u00edsima, Estado de Durango, el 6 de junio de 1942. Realiz\u00f3 sus estudios primarios en la Escuela Primaria de La Pur\u00edsima y en 1955 ingres\u00f3 en el Seminario Conciliar de Durango, donde curs\u00f3 los estudios de Humanidades, Filosof\u00eda y un a\u00f1o de Teolog\u00eda.<\/p>\n<p>En el a\u00f1o 1962 ingres\u00f3 en el Colegio P\u00edo Latino Americano para cursar la Licenciatura en Teolog\u00eda Dogm\u00e1tica en la Universidad Gregoriana de Roma.<\/p>\n<p>Recibi\u00f3 la ordenaci\u00f3n sacerdotal en Roma el 3 de julio de 1966. Despu\u00e9s de desempe\u00f1ar diversos cargos pastorales como presb\u00edtero, fue nombrado Obispo de Tehuac\u00e1n el 7 de noviembre de 1985. Se consagr\u00f3 el 21 de diciembre de ese mismo a\u00f1o en el Seminario Menor de Tehuac\u00e1n.<\/p>\n<p>El 13 de junio de 1995 fue elegido Arzobispo Primado de M\u00e9xico. Tom\u00f3 posesi\u00f3n de la Arquidi\u00f3cesis el 26 de julio de ese mismo a\u00f1o. El 21 de febrero de 1998 fue creado Cardenal.<\/p>\n<p>Tambi\u00e9n te puede interesar:<\/p>\n<p>El Papa nombr\u00f3 al Cardenal Carlos Aguiar nuevo Arzobispo de M\u00e9xico https:\/\/t.co\/XfXspZr0tR<\/p>\n<p>Fuente: AciPrensa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00c9XICO, 07 Dic. 17 (ACI).- Luego de conocerse el nombramiento del Cardenal Carlos Aguiar como&hellip;<\/p>\n","protected":false},"author":1,"featured_media":5459,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-5453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts\/5453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/comments?post=5453"}],"version-history":[{"count":0,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts\/5453\/revisions"}],"wp:attachment":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/media?parent=5453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/categories?post=5453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/tags?post=5453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}