{"id":5561,"date":"2017-12-10T23:46:43","date_gmt":"2017-12-11T04:16:43","guid":{"rendered":"https:\/\/www.diariocatolico.org\/?p=5561"},"modified":"2026-04-17T15:04:05","modified_gmt":"2026-04-17T15:04:05","slug":"la-santa-sede-pide-respeto-status-quo-tierra-santa","status":"publish","type":"post","link":"https:\/\/diariocatolico.org\/index.php\/2017\/12\/10\/la-santa-sede-pide-respeto-status-quo-tierra-santa\/","title":{"rendered":"La Santa Sede pide respeto por el status quo en Tierra Santa"},"content":{"rendered":"<p>La Santa Sede sigue con gran atenci\u00f3n la <b>evoluci\u00f3n de la situaci\u00f3n en Oriente Medio<\/b>, de modo especial en Jerusal\u00e9n, <b>ciudad sagrada <\/b>para cristianos, jud\u00edos y musulmanes de todo el mundo.<\/p>\n<p>Tal y como se lee en el comunicado publicado por la oficina de prensa de la Santa Sede, &#8220;expresando su dolor por los enfrentamientos que se han cobrado la vida de numerosas v\u00edctimas en los \u00faltimos d\u00edas, el Santo Padre renueva su<b> llamamiento a la sabidur\u00eda y la prudencia de todos<\/b>, y eleva fervientes oraciones con el fin de que los l\u00edderes de las naciones, en este momento de particular gravedad, se comprometan a evitar una nueva espiral de violencia, respondiendo con palabras y hechos, a los anhelos de paz, justicia y seguridad de las poblaciones de esa tierra atormentada&#8221;.<\/p>\n<p>Las preocupaciones sobre las perspectivas de paz en la regi\u00f3n han sido objeto de diversas iniciativas en los \u00faltimos d\u00edas, incluidas las urgentes reuniones convocadas por la<b> Liga \u00c1rabe y la Organizaci\u00f3n para la Cooperaci\u00f3n Isl\u00e1mica<\/b>.<\/p>\n<p>La Santa Sede es sensible a estas preocupaciones y, recordando las sentidas palabras del Papa Francisco, reitera su conocida posici\u00f3n con respecto al car\u00e1cter singular de la Ciudad Santa y la ineludibilidad del <b>respeto por el status quo<\/b>, en conformidad con las deliberaciones de la comunidad internacional y las reiteradas peticiones de las jerarqu\u00edas de las Iglesias y de las comunidades cristianas de Tierra Santa.<\/p>\n<p>Al mismo tiempo, reitera su convicci\u00f3n de que solo una soluci\u00f3n negociada entre israel\u00edes y palestinos puede conducir a una paz estable y duradera y garantizar as\u00ed, la coexistencia pac\u00edfica de <b>dos estados dentro de fronteras reconocidas<\/b> internacionalmente.<\/p>\n<p><a href=\"http:\/\/es.radiovaticana.va\/news\/2017\/12\/10\/comunicado_santa_sede_respeto_status_quo_\/1354006\">(from Vatican Radio)<\/a><br \/>\nFuente: Vaticano.va<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Santa Sede sigue con gran atenci\u00f3n la evoluci\u00f3n de la situaci\u00f3n en Oriente Medio,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":5562,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-5561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts\/5561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/comments?post=5561"}],"version-history":[{"count":0,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts\/5561\/revisions"}],"wp:attachment":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/media?parent=5561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/categories?post=5561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/tags?post=5561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}