{"id":6997,"date":"2018-01-24T10:00:31","date_gmt":"2018-01-24T14:30:31","guid":{"rendered":"https:\/\/www.diariocatolico.org\/?p=6997"},"modified":"2026-04-17T15:04:05","modified_gmt":"2026-04-17T15:04:05","slug":"mensaje-del-santo-padre-francisco-la-52-jornada-mundial-las-comunicaciones-sociales","status":"publish","type":"post","link":"https:\/\/diariocatolico.org\/index.php\/2018\/01\/24\/mensaje-del-santo-padre-francisco-la-52-jornada-mundial-las-comunicaciones-sociales\/","title":{"rendered":"MENSAJE DEL SANTO PADRE FRANCISCO PARA LA 52 JORNADA MUNDIAL DE LAS COMUNICACIONES SOCIALES"},"content":{"rendered":"<p align=\"center\"><span style=\"color: #663300; font-size: large;\"><b><i>MENSAJE DEL SANTO PADRE FRANCISCO<br \/>\nPARA LA 52 JORNADA MUNDIAL<br \/>\nDE LAS COMUNICACIONES SOCIALES<\/i><\/b><\/span><\/p>\n<p align=\"center\"><span style=\"color: #663300;\"><b>\u00abLa verdad os har\u00e1 libres\u00bb\u00a0(<i>Jn<\/i>\u00a08, 32).<br \/>\n<i>Fake news<\/i>\u00a0y periodismo de paz<\/b><\/span><\/p>\n<p><!--more--><\/p>\n<p><i>Queridos hermanos y hermanas:<\/i><\/p>\n<p>En el proyecto de Dios, la comunicaci\u00f3n humana es una modalidad esencial para vivir la comuni\u00f3n. El ser humano, imagen y semejanza del Creador, es capaz de expresar y compartir la verdad, el bien, la belleza. Es capaz de contar su propia experiencia y describir el mundo, y de construir as\u00ed la memoria y la comprensi\u00f3n de los acontecimientos.<\/p>\n<p>Pero el hombre, si sigue su propio ego\u00edsmo orgulloso, puede tambi\u00e9n hacer un mal uso de la facultad de comunicar, como muestran desde el principio los episodios b\u00edblicos de Ca\u00edn y Abel, y de la Torre de Babel (cf.\u00a0<i>Gn<\/i>\u00a04,1-16; 11,1-9). La alteraci\u00f3n de la verdad es el s\u00edntoma t\u00edpico de tal distorsi\u00f3n, tanto en el plano individual como en el colectivo. Por el contrario, en la fidelidad a la l\u00f3gica de Dios, la comunicaci\u00f3n se convierte en lugar para expresar la propia responsabilidad en la b\u00fasqueda de la verdad y en la construcci\u00f3n del bien.<\/p>\n<p>Hoy, en un contexto de comunicaci\u00f3n cada vez m\u00e1s veloz e inmersos dentro de un sistema digital, asistimos al fen\u00f3meno de las noticias falsas, las llamadas \u00ab<i>fake news<\/i>\u00bb. Dicho fen\u00f3meno nos llama a la reflexi\u00f3n; por eso he dedicado este mensaje al tema de la verdad, como ya hicieron en diversas ocasiones mis predecesores a partir de\u00a0<a href=\"http:\/\/w2.vatican.va\/content\/paul-vi\/es.html\">Pablo VI<\/a>\u00a0(cf.\u00a0<a href=\"http:\/\/w2.vatican.va\/content\/paul-vi\/es\/messages\/communications\/documents\/hf_p-vi_mes_19720421_vi-com-day.html\"><i>Mensaje de<\/i>\u00a01972:\u00a0<i>\u00abLos instrumentos de comunicaci\u00f3n social al servicio de la verdad\u00bb<\/i><\/a><i>).<\/i>\u00a0Quisiera ofrecer de este modo una aportaci\u00f3n al esfuerzo com\u00fan para prevenir la difusi\u00f3n de las noticias falsas, y para redescubrir el valor de la profesi\u00f3n period\u00edstica y la responsabilidad personal de cada uno en la comunicaci\u00f3n de la verdad.<\/p>\n<p>1.<i>\u00a0\u00bfQu\u00e9 hay de falso en las \u00abnoticias\u00a0 falsas\u00bb?<\/i><\/p>\n<p><i>\u00abFake news\u00bb<\/i>\u00a0es un t\u00e9rmino discutido y tambi\u00e9n objeto de debate. Generalmente alude a la desinformaci\u00f3n difundida\u00a0<i>online<\/i>\u00a0o en los medios de comunicaci\u00f3n tradicionales. Esta expresi\u00f3n se refiere, por tanto, a informaciones infundadas, basadas en datos inexistentes o distorsionados, que tienen como finalidad enga\u00f1ar o incluso manipular al lector para alcanzar determinados objetivos, influenciar las decisiones pol\u00edticas u obtener ganancias econ\u00f3micas.<\/p>\n<p>La eficacia de las\u00a0<i>fake news<\/i>\u00a0se debe, en primer lugar, a su\u00a0<i>naturaleza mim\u00e9tica<\/i>, es decir, a su capacidad de aparecer como plausibles. En segundo lugar, estas noticias, falsas pero veros\u00edmiles, son capciosas, en el sentido de que son h\u00e1biles para capturar la atenci\u00f3n de los destinatarios poniendo el acento en estereotipos y prejuicios extendidos dentro de un tejido social, y se apoyan en emociones f\u00e1ciles de suscitar, como el ansia, el desprecio, la rabia y la frustraci\u00f3n. Su difusi\u00f3n puede contar con el uso manipulador de las redes sociales y de las l\u00f3gicas que garantizan su funcionamiento. De este modo, los contenidos, a pesar de carecer de fundamento, obtienen una visibilidad tal que incluso los desmentidos oficiales dif\u00edcilmente consiguen contener los da\u00f1os que producen.<\/p>\n<p>La dificultad para desenmascarar y erradicar las\u00a0<i>fake news<\/i>\u00a0se debe asimismo al hecho de que las personas a menudo interact\u00faan dentro de ambientes digitales homog\u00e9neos e impermeables a perspectivas y opiniones divergentes. El resultado de esta\u00a0<i>l\u00f3gica de la desinformaci\u00f3n<\/i>\u00a0es que, en lugar de realizar una sana comparaci\u00f3n con otras fuentes de informaci\u00f3n, lo que podr\u00eda poner en discusi\u00f3n positivamente los prejuicios y abrir un di\u00e1logo constructivo, se corre el riesgo de convertirse en actores involuntarios de la difusi\u00f3n de opiniones sectarias e infundadas. El drama de la desinformaci\u00f3n es el desacreditar al otro, el presentarlo como enemigo, hasta llegar a la demonizaci\u00f3n que favorece los conflictos. Las noticias falsas revelan as\u00ed la presencia de actitudes intolerantes e hipersensibles al mismo tiempo, con el \u00fanico resultado de extender el peligro de la arrogancia y el odio. A esto conduce, en \u00faltimo an\u00e1lisis, la falsedad.<\/p>\n<p>2.<i>\u00a0\u00bfC\u00f3mo podemos reconocerlas?<\/i><\/p>\n<p>Ninguno de nosotros puede eximirse de la responsabilidad de hacer frente a estas falsedades. No es tarea f\u00e1cil, porque la desinformaci\u00f3n se basa frecuentemente en discursos heterog\u00e9neos, intencionadamente evasivos y sutilmente enga\u00f1osos, y se sirve a veces de mecanismos refinados. Por eso son loables las iniciativas educativas que permiten aprender a leer y valorar el contexto comunicativo, y ense\u00f1an a no ser divulgadores inconscientes de la desinformaci\u00f3n, sino activos en su desvelamiento. Son asimismo encomiables las iniciativas institucionales y jur\u00eddicas encaminadas a concretar normas que se opongan a este fen\u00f3meno, as\u00ed como las que han puesto en marcha las compa\u00f1\u00edas tecnol\u00f3gicas y de medios de comunicaci\u00f3n, dirigidas a definir nuevos criterios para la verificaci\u00f3n de las identidades personales que se esconden detr\u00e1s de\u00a0 millones de perfiles digitales.<\/p>\n<p>Pero la prevenci\u00f3n y la identificaci\u00f3n de los mecanismos de la desinformaci\u00f3n requieren tambi\u00e9n un discernimiento atento y profundo. En efecto, se ha de desenmascarar la que se podr\u00eda definir como la \u00abl\u00f3gica de la serpiente\u00bb, capaz de camuflarse en todas partes y morder. Se trata de la estrategia utilizada por la \u00abserpiente astuta\u00bb de la que habla el\u00a0<i>Libro del G\u00e9nesis<\/i>, la cual, en los albores de la humanidad, fue la art\u00edfice de la primera\u00a0<i>fake news<\/i>\u00a0(cf.\u00a0<i>Gn<\/i>\u00a03,1-15), que llev\u00f3 a las tr\u00e1gicas consecuencias del pecado, y que se concretizaron luego en el primer fratricidio (cf.\u00a0<i>Gn<\/i>\u00a04) y en otras innumerables formas de mal contra Dios, el pr\u00f3jimo, la sociedad y la creaci\u00f3n.<\/p>\n<p>La estrategia de este h\u00e1bil \u00abpadre de la mentira\u00bb (<i>Jn<\/i>\u00a08,44) es la\u00a0<i>m\u00edmesis<\/i>, una insidiosa y peligrosa seducci\u00f3n que se abre camino en el coraz\u00f3n del hombre con argumentaciones falsas y atrayentes. En la narraci\u00f3n del pecado original, el tentador, efectivamente, se acerca a la mujer fingiendo ser su amigo e interesarse por su bien, y comienza su discurso con una afirmaci\u00f3n verdadera, pero s\u00f3lo en parte:\u00ab\u00bfConque Dios os ha dicho que no com\u00e1is de ning\u00fan \u00e1rbol del jard\u00edn?\u00bb (<i>Gn<\/i>\u00a03,1). En realidad, lo que Dios hab\u00eda dicho a Ad\u00e1n no era que no comieran de\u00a0<i>ning\u00fan \u00e1rbol<\/i>, sino tan solo de\u00a0<i>un \u00e1rbol<\/i>: \u00abDel \u00e1rbol del conocimiento del bien y el mal no comer\u00e1s\u00bb (<i>Gn<\/i>\u00a02,17). La mujer, respondiendo, se lo explica a la serpiente, pero se deja atraer por su provocaci\u00f3n:\u00abPodemos comer los frutos de los \u00e1rboles del jard\u00edn; pero del fruto del \u00e1rbol que est\u00e1 en mitad del jard\u00edn nos ha dicho Dios: \u201cNo com\u00e1is de \u00e9l ni lo toqu\u00e9is, de lo contrario morir\u00e9is\u201d\u00bb (<i>Gn\u00a0<\/i>3,2). Esta respuesta tiene un sabor legalista y pesimista: habiendo dado credibilidad al falsario y dej\u00e1ndose seducir por su versi\u00f3n de los hechos, la mujer se deja enga\u00f1ar. Por eso, enseguida presta atenci\u00f3n cuando le asegura: \u00abNo, no morir\u00e9is\u00bb (<i>v.\u00a0<\/i>4). Luego, la deconstrucci\u00f3n del tentador asume una apariencia cre\u00edble: \u00abDios sabe que el d\u00eda en que com\u00e1is de \u00e9l, se os abrir\u00e1n los ojos, y ser\u00e9is como Dios en el conocimiento del bien y el mal\u00bb (v. 5). Finalmente, se llega a desacreditar la recomendaci\u00f3n paternal de Dios, que estaba dirigida al bien, para seguir la seductora incitaci\u00f3n del enemigo: \u00abLa mujer se dio cuenta de que el \u00e1rbol era bueno de comer, atrayente a los ojos y deseable\u00bb (v. 6).\u00a0 Este episodio b\u00edblico revela por tanto un hecho esencial para nuestro razonamiento: ninguna desinformaci\u00f3n es inocua; por el contrario, fiarse de lo que es falso produce consecuencias nefastas. Incluso una distorsi\u00f3n de la verdad aparentemente leve puede tener efectos peligrosos.<\/p>\n<p>De lo que se trata, de hecho, es de nuestra codicia. Las\u00a0<i>fake news<\/i>\u00a0se convierten a menudo en virales, es decir, se difunden de modo veloz y dif\u00edcilmente manejable, no a causa de la l\u00f3gica de compartir que caracteriza a las redes sociales, sino m\u00e1s bien por la codicia insaciable que se enciende f\u00e1cilmente en el ser humano.<\/p>\n<p>Las mismas motivaciones econ\u00f3micas y oportunistas de la desinformaci\u00f3n tienen su ra\u00edz en la sed de poder, de tener y de gozar que en \u00faltimo t\u00e9rmino nos hace v\u00edctimas de un enga\u00f1o mucho m\u00e1s tr\u00e1gico que el de sus manifestaciones individuales: el del mal que se mueve de falsedad en falsedad para robarnos la libertad del coraz\u00f3n. He aqu\u00ed porqu\u00e9 educar en la verdad significa educar para saber discernir, valorar y ponderar los deseos y las inclinaciones que se mueven dentro de nosotros, para no encontrarnos privados del bien \u00abcayendo\u00bb en cada tentaci\u00f3n.<\/p>\n<p>3. \u00ab<i>La verdad os har\u00e1 libres<\/i>\u00bb (<i>Jn<\/i>\u00a08,32)<\/p>\n<p>La continua contaminaci\u00f3n a trav\u00e9s de un lenguaje enga\u00f1oso termina por ofuscar la interioridad de la persona. Dostoyevski escribi\u00f3 algo interesante en este \u00a0sentido: \u00abQuien se miente a s\u00ed mismo y escucha sus propias mentiras, llega al punto de no poder distinguir la verdad, ni dentro de s\u00ed mismo ni en torno a s\u00ed, y de este modo comienza a perder el respeto a s\u00ed mismo y a los dem\u00e1s. Luego, como ya no estima a nadie, deja tambi\u00e9n de amar, y para distraer el tedio que produce la falta de cari\u00f1o y ocuparse en algo, se entrega a las pasiones y a los placeres m\u00e1s bajos; y por culpa de sus vicios, se hace como una bestia. Y todo esto deriva del continuo mentir a los dem\u00e1s y a s\u00ed mismo\u00bb (<i>Los hermanos Karamazov,<\/i>\u00a0II,2).<\/p>\n<p>Entonces, \u00bfc\u00f3mo defendernos? El ant\u00eddoto m\u00e1s eficaz contra el virus de la falsedad es dejarse purificar por la verdad. En la visi\u00f3n cristiana, la verdad no es s\u00f3lo una realidad conceptual que se refiere al juicio sobre las cosas, defini\u00e9ndolas como verdaderas o falsas. La verdad no es solamente el sacar a la luz cosas oscuras, \u00abdesvelar la realidad\u00bb, como lleva a pensar el antiguo t\u00e9rmino griego que la designa,\u00a0<i>aletheia<\/i>\u00a0(de\u00a0<i>a-leth\u00e8s,\u00a0<\/i>\u00abno escondido\u00bb). La verdad tiene que ver con la vida entera. En la Biblia tiene el significado de apoyo, solidez, confianza, como da a entender la ra\u00edz \u2018<i>aman<\/i>, de la cual procede tambi\u00e9n el\u00a0<i>Am\u00e9n<\/i>\u00a0lit\u00fargico. La verdad es aquello sobre lo que uno se puede apoyar para no caer. En este sentido relacional, el \u00fanico verdaderamente fiable y digno de confianza, sobre el que se puede contar siempre, es decir, \u00abverdadero\u00bb, es el Dios vivo. He aqu\u00ed la afirmaci\u00f3n de Jes\u00fas: \u00ab<i>Yo soy<\/i>\u00a0la verdad\u00bb (<i>Jn<\/i>\u00a014,6). El hombre, por tanto, descubre y redescubre la verdad cuando la experimenta en s\u00ed mismo como fidelidad y fiabilidad de quien lo ama. S\u00f3lo esto libera al hombre: \u00abLa verdad os har\u00e1 libres\u00bb (<i>Jn<\/i>\u00a08,32).<\/p>\n<p>Liberaci\u00f3n de la falsedad y b\u00fasqueda de la relaci\u00f3n: he aqu\u00ed los dos ingredientes que no pueden faltar para que nuestras palabras y nuestros gestos sean verdaderos, aut\u00e9nticos, dignos de confianza. Para discernir la verdad es preciso distinguir lo que favorece la comuni\u00f3n y promueve el bien, y lo que, por el contrario, tiende a aislar, dividir y contraponer. La verdad, por tanto, no se alcanza realmente cuando se impone como algo extr\u00ednseco e impersonal; en cambio, brota de relaciones libres entre las personas, en la escucha rec\u00edproca. Adem\u00e1s, nunca se deja de buscar la verdad, porque siempre est\u00e1 al acecho la falsedad, tambi\u00e9n cuando se dicen cosas verdaderas. Una argumentaci\u00f3n impecable puede apoyarse sobre hechos innegables, pero si se utiliza para herir a otro y desacreditarlo a los ojos de los dem\u00e1s, por m\u00e1s que parezca justa, no contiene en s\u00ed la verdad. Por sus frutos podemos distinguir la verdad de los enunciados: si suscitan pol\u00e9mica, fomentan divisiones, infunden resignaci\u00f3n; o si, por el contrario, llevan a la reflexi\u00f3n consciente y madura, al di\u00e1logo constructivo, a una laboriosidad provechosa.<\/p>\n<p>4<i>. La paz es la verdadera noticia<\/i><\/p>\n<p>El mejor ant\u00eddoto contra las falsedades no son las estrategias, sino las personas, personas que, libres de la codicia, est\u00e1n dispuestas a escuchar, y permiten que la verdad emerja a trav\u00e9s de la fatiga de un di\u00e1logo sincero; personas que, atra\u00eddas por el bien, se responsabilizan en el uso del lenguaje. Si el camino para evitar la expansi\u00f3n de la desinformaci\u00f3n es la responsabilidad, quien tiene un compromiso especial es el que por su oficio tiene la responsabilidad de informar, es decir: el periodista,\u00a0<i>custodio de las noticias<\/i>. Este, en el mundo contempor\u00e1neo, no realiza s\u00f3lo un trabajo, sino una verdadera y propia misi\u00f3n. Tiene la tarea, en el frenes\u00ed de las noticias y en el torbellino de las primicias, de recordar que en el centro de la noticia no est\u00e1 la velocidad en darla y el impacto sobre las cifras de audiencia, sino\u00a0<i>las personas<\/i>. Informar es formar, es involucrarse en la vida de las personas. Por eso la verificaci\u00f3n de las fuentes y la custodia de la comunicaci\u00f3n son verdaderos y propios procesos de desarrollo del bien que generan confianza y abren caminos de comuni\u00f3n y de paz.<\/p>\n<p>Por lo tanto, deseo dirigir un llamamiento a promover un\u00a0<i>periodismo de paz<\/i>, sin entender con esta expresi\u00f3n un periodismo \u00abbuenista\u00bb que niegue la existencia de problemas graves y asuma tonos empalagosos. Me refiero, por el contrario, a un periodismo sin fingimientos, hostil a las falsedades, a esl\u00f3ganes efectistas y a declaraciones altisonantes; un periodismo hecho por personas para personas, y que se comprende como servicio a todos, especialmente a aquellos \u2013y son la mayor\u00eda en el mundo\u2013 que no tienen voz; un periodismo que no queme las noticias, sino que se esfuerce en buscar las causas reales de los conflictos, para favorecer la comprensi\u00f3n de sus ra\u00edces y su superaci\u00f3n a trav\u00e9s de la puesta en marcha de procesos virtuosos; un periodismo empe\u00f1ado en indicar soluciones alternativas a la escalada<i>\u00a0<\/i>del clamor y de la violencia verbal.<\/p>\n<p>Por eso, inspir\u00e1ndonos en una oraci\u00f3n franciscana, podr\u00edamos dirigirnos a la Verdad en persona de la siguiente manera:<\/p>\n<p><i>Se\u00f1or, haznos instrumentos de tu paz.<br \/>\nHaznos reconocer el mal que se insin\u00faa en una comunicaci\u00f3n que no crea comuni\u00f3n.<br \/>\nHaznos capaces de quitar el veneno de nuestros juicios.<br \/>\nAy\u00fadanos a hablar de los otros como de hermanos y hermanas.<br \/>\nT\u00fa eres fiel y digno de confianza; haz que nuestras palabras sean semillas de bien para el mundo:<br \/>\ndonde hay\u00a0ruido, haz que practiquemos la escucha;<br \/>\ndonde hay confusi\u00f3n, haz que inspiremos armon\u00eda;<br \/>\ndonde hay ambig\u00fcedad, haz que llevemos claridad;<br \/>\ndonde hay exclusi\u00f3n, haz que llevemos el compartir;<br \/>\ndonde hay sensacionalismo, haz que usemos la sobriedad;<br \/>\ndonde hay superficialidad, haz que planteemos interrogantes verdaderos;<br \/>\ndonde hay prejuicio, haz que suscitemos confianza;<br \/>\ndonde hay agresividad, haz que llevemos respeto;<br \/>\ndonde hay falsedad, haz que llevemos verdad.<\/i><\/p>\n<p><i>Am\u00e9n.<\/i><\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><b>Francisco<\/b><\/p>\n<p style=\"text-align: left;\" align=\"center\">Fuente: <a href=\"http:\/\/w2.vatican.va\/content\/francesco\/es\/messages\/communications\/documents\/papa-francesco_20180124_messaggio-comunicazioni-sociali.html\">Vatican.va<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MENSAJE DEL SANTO PADRE FRANCISCO PARA LA 52 JORNADA MUNDIAL DE LAS COMUNICACIONES SOCIALES \u00abLa&hellip;<\/p>\n","protected":false},"author":1,"featured_media":6986,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-6997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts\/6997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/comments?post=6997"}],"version-history":[{"count":0,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts\/6997\/revisions"}],"wp:attachment":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/media?parent=6997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/categories?post=6997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/tags?post=6997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}