{"id":85418,"date":"2021-11-12T22:36:59","date_gmt":"2021-11-13T02:36:59","guid":{"rendered":"https:\/\/www.diariocatolico.org\/?p=85418"},"modified":"2026-04-17T15:05:43","modified_gmt":"2026-04-17T15:05:43","slug":"pastoral-de-la-salud-se-reune-con-vicepresidenta-y-director-de-sns-para-presentar-trabajos-realizados-red-de-dispensarios-y-otros-temas","status":"publish","type":"post","link":"https:\/\/diariocatolico.org\/index.php\/2021\/11\/12\/pastoral-de-la-salud-se-reune-con-vicepresidenta-y-director-de-sns-para-presentar-trabajos-realizados-red-de-dispensarios-y-otros-temas\/","title":{"rendered":"Pastoral de la Salud se re\u00fane con Vicepresidenta y Director de SNS para presentar trabajos realizados, Red de Dispensarios y otros temas"},"content":{"rendered":"<p style=\"text-align: justify;\">En el d\u00eda de hoy Sor Trinidad Ayala (Sor Trini) Coordinadora General de La Pastoral de la Salud de la Arquidi\u00f3cesis de Santo Domingo, sostuvo una reuni\u00f3n con la Vicepresidenta de la Rep\u00fablica, Raquel Pe\u00f1a y el Dr. Mario Lama, \u00a0Director del Sistema Nacional de Salud (SNS).<\/p>\n<p style=\"text-align: justify;\">Luego de una oraci\u00f3n de inicio y reflexi\u00f3n de la palabra del d\u00eda, realizada por Sor Trini, el Dr. Cesan Iv\u00e1n Feris, realiz\u00f3 la presentaci\u00f3n de los representantes de la Pastoral de la Salud.<\/p>\n<p style=\"text-align: justify;\">Sor Trini hizo una introducci\u00f3n donde mencion\u00f3 el reconocimiento a la calidad de la pastoral como ASFL, hizo menci\u00f3n de que PROMESECAL no entrega medicamentos a la Pastoral.<\/p>\n<p style=\"text-align: justify;\">Los temas agotados en la agenda de trabajo fueron:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Red de Dispensarios<\/li>\n<li>Dispensario Salud Mental Nuestra Se\u00f1ora De Lourdes<\/li>\n<li>Asistencia en salud mental a ciudadanos en conflicto con la ley<\/li>\n<li>Acuerdo con la Pontificia Universidad Cat\u00f3lica para formar Agentes de Pastoral<\/li>\n<li>Acuerdo con el Consejo Nacional de Drogas para formar l\u00edderes comunitarios en prevenci\u00f3n del consumo y abordaje a los pacientes.<\/li>\n<li>Proyecto con el SIUBEN para captar personas necesitadas e integrarlas en sus programas.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-85420 alignleft\" src=\"https:\/\/www.diariocatolico.org\/wp-content\/uploads\/2021\/11\/23-300x212.jpeg\" alt=\"\" width=\"300\" height=\"212\" \/>Se plantearon adem\u00e1s las siguientes propuestas:<\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li>Actualizaci\u00f3n del registro de los establecimientos de la red de centros de la iglesia cat\u00f3lica<\/li>\n<li>Presentaci\u00f3n del Contrato de Gesti\u00f3n entre el SNS y la Pastoral de la Salud Arquidiocesana.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">El Dr. Mario Lama director del SNS, propuso hacer sesiones de trabajo para ir enfrentando las diversas problem\u00e1ticas, mientras que la Vicepresidenta Raquel Pe\u00f1a se comprometi\u00f3 a hablar con los directivos del SENASA Y PROMESECAL para que se pongan en contacto con la pastoral\u00a0 y resolver las situaciones\u00a0 pendientes.<\/p>\n<p style=\"text-align: justify;\">Solicit\u00f3 que, en las sesiones de trabajo entre el SNS y La Pastoral de la Salud, se haga un levantamiento para conocer las necesidades y presentarlas a la presidencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el d\u00eda de hoy Sor Trinidad Ayala (Sor Trini) Coordinadora General de La Pastoral&hellip;<\/p>\n","protected":false},"author":1,"featured_media":85419,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-85418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts\/85418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/comments?post=85418"}],"version-history":[{"count":0,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/posts\/85418\/revisions"}],"wp:attachment":[{"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/media?parent=85418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/categories?post=85418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariocatolico.org\/index.php\/wp-json\/wp\/v2\/tags?post=85418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}